{"id":28045,"date":"2017-02-12T12:21:14","date_gmt":"2017-02-12T08:21:14","guid":{"rendered":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice.jpg"},"modified":"2017-02-12T12:21:14","modified_gmt":"2017-02-12T08:21:14","slug":"ecologie-maurice-2","status":"inherit","type":"attachment","link":"https:\/\/www.lagazette-mag.io\/en\/ecologie-maurice-2\/","title":{"rendered":"Ecologie-Maurice"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-28045","attachment","type-attachment","status-inherit"],"aioseo_notices":[],"amp_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"187\" src=\"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-300x187.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-150x93@2x.jpg 300w, https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-150x93.jpg 150w, https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-696x434.jpg 696w, https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-500x312.jpg 500w, https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice.jpg 945w, https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-300x187@2x.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":945,"height":589,"file":"Ecologie-Maurice.jpg","sizes":{"medium":{"file":"Ecologie-Maurice-300x187.jpg","width":300,"height":187,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-300x187.jpg"},"thumbnail":{"file":"Ecologie-Maurice-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-150x150.jpg"},"td_150x0":{"file":"Ecologie-Maurice-150x93.jpg","width":150,"height":93,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-150x93.jpg"},"td_218x150":{"file":"Ecologie-Maurice-218x150.jpg","width":218,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-218x150.jpg"},"td_300x0":{"file":"Ecologie-Maurice-300x187.jpg","width":300,"height":187,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-300x187.jpg"},"td_324x400":{"file":"Ecologie-Maurice-324x400.jpg","width":324,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-324x400.jpg"},"td_485x360":{"file":"Ecologie-Maurice-485x360.jpg","width":485,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-485x360.jpg"},"td_696x0":{"file":"Ecologie-Maurice-696x434.jpg","width":696,"height":434,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-696x434.jpg"},"bd-large":{"file":"Ecologie-Maurice-560x370.jpg","width":560,"height":370,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-560x370.jpg"},"gg_gallery_thumbnail":{"file":"Ecologie-Maurice-450x250.jpg","width":450,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-450x250.jpg"},"bd-small":{"file":"Ecologie-Maurice-90x68.jpg","width":90,"height":68,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-90x68.jpg"},"bd-medium":{"file":"Ecologie-Maurice-310x165.jpg","width":310,"height":165,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-310x165.jpg"},"bd-big":{"file":"Ecologie-Maurice-945x526.jpg","width":945,"height":526,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-945x526.jpg"},"bd-normal":{"file":"Ecologie-Maurice-660x330.jpg","width":660,"height":330,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-660x330.jpg"},"post-thumbnail":{"file":"Ecologie-Maurice-660x330.jpg","width":660,"height":330,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-660x330.jpg"},"wpbdp-mini":{"file":"Ecologie-Maurice-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-50x50.jpg"},"wpbdp-thumb":{"file":"Ecologie-Maurice-150x93.jpg","width":150,"height":93,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-150x93.jpg"},"wpbdp-large":{"file":"Ecologie-Maurice-500x312.jpg","width":500,"height":312,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice-500x312.jpg"},"full":{"file":"Ecologie-Maurice.jpg","width":945,"height":589,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/Ecologie-Maurice.jpg","_links":{"self":[{"href":"https:\/\/www.lagazette-mag.io\/en\/wp-json\/wp\/v2\/media\/28045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lagazette-mag.io\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.lagazette-mag.io\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.lagazette-mag.io\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lagazette-mag.io\/en\/wp-json\/wp\/v2\/comments?post=28045"}]}}