{"id":32325,"date":"2018-09-05T15:19:18","date_gmt":"2018-09-05T11:19:18","guid":{"rendered":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4.jpg"},"modified":"2018-09-05T15:19:18","modified_gmt":"2018-09-05T11:19:18","slug":"unnameddeco4-2","status":"inherit","type":"attachment","link":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/","title":{"rendered":"unnamedDe\u0301co4"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-32325","attachment","type-attachment","status-inherit"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"La R\u00e9daction de La Gazette\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La Gazette Mag\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"unnamedDe\u0301co4\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-09-05T11:19:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-09-05T11:19:18+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lagazettemagoceanindien\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"unnamedDe\u0301co4\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/unnameddeco4-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/unnameddeco4-2\\\/#listItem\",\"name\":\"unnamedDe\\u0301co4\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/unnameddeco4-2\\\/#listItem\",\"position\":2,\"name\":\"unnamedDe\\u0301co4\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/unnameddeco4-2\\\/#itempage\",\"url\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/unnameddeco4-2\\\/\",\"name\":\"unnamedDe\\u0301co4\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/unnameddeco4-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/author\\\/la-redaction\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/author\\\/la-redaction\\\/#author\"},\"datePublished\":\"2018-09-05T15:19:18+04:00\",\"dateModified\":\"2018-09-05T15:19:18+04:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/#organization\",\"name\":\"La Gazette Mag\",\"description\":\"Le Mensuel Gratuit de l'oc\\u00e9an indien\",\"url\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/\",\"telephone\":\"+23059757222\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lagazettemagoceanindien\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/author\\\/la-redaction\\\/#author\",\"url\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/author\\\/la-redaction\\\/\",\"name\":\"La R\\u00e9daction de La Gazette\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/unnameddeco4-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.lagazette-mag.io\\\/wp-content\\\/uploads\\\/favicon-la-gazette-mag.png\",\"width\":96,\"height\":96,\"caption\":\"La R\\u00e9daction de La Gazette\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/\",\"name\":\"La Gazette Mag\",\"description\":\"Le Mensuel Gratuit de l'oc\\u00e9an indien\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lagazette-mag.io\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"unnamedDe\u0301co4","description":"","canonical_url":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.lagazette-mag.io\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/www.lagazette-mag.io\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/#listItem","name":"unnamedDe\u0301co4"}},{"@type":"ListItem","@id":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/#listItem","position":2,"name":"unnamedDe\u0301co4","previousItem":{"@type":"ListItem","@id":"https:\/\/www.lagazette-mag.io\/en\/#listItem","name":"Home"}}]},{"@type":"ItemPage","@id":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/#itempage","url":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/","name":"unnamedDe\u0301co4","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.lagazette-mag.io\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/#breadcrumblist"},"author":{"@id":"https:\/\/www.lagazette-mag.io\/en\/author\/la-redaction\/#author"},"creator":{"@id":"https:\/\/www.lagazette-mag.io\/en\/author\/la-redaction\/#author"},"datePublished":"2018-09-05T15:19:18+04:00","dateModified":"2018-09-05T15:19:18+04:00"},{"@type":"Organization","@id":"https:\/\/www.lagazette-mag.io\/en\/#organization","name":"La Gazette Mag","description":"Le Mensuel Gratuit de l'oc\u00e9an indien","url":"https:\/\/www.lagazette-mag.io\/en\/","telephone":"+23059757222","sameAs":["https:\/\/www.facebook.com\/lagazettemagoceanindien"]},{"@type":"Person","@id":"https:\/\/www.lagazette-mag.io\/en\/author\/la-redaction\/#author","url":"https:\/\/www.lagazette-mag.io\/en\/author\/la-redaction\/","name":"La R\u00e9daction de La Gazette","image":{"@type":"ImageObject","@id":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/#authorImage","url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/favicon-la-gazette-mag.png","width":96,"height":96,"caption":"La R\u00e9daction de La Gazette"}},{"@type":"WebSite","@id":"https:\/\/www.lagazette-mag.io\/en\/#website","url":"https:\/\/www.lagazette-mag.io\/en\/","name":"La Gazette Mag","description":"Le Mensuel Gratuit de l'oc\u00e9an indien","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.lagazette-mag.io\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"La Gazette Mag","og:type":"article","og:title":"unnamedDe\u0301co4","og:url":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/","article:published_time":"2018-09-05T11:19:18+00:00","article:modified_time":"2018-09-05T11:19:18+00:00","article:publisher":"https:\/\/www.facebook.com\/lagazettemagoceanindien","twitter:card":"summary","twitter:title":"unnamedDe\u0301co4"},"aioseo_meta_data":{"post_id":"32325","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-02-24 15:55:14","updated":"2025-06-04 17:28:53","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.lagazette-mag.io\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tunnamedDe\u0301co4\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.lagazette-mag.io\/en\/"},{"label":"unnamedDe\u0301co4","link":"https:\/\/www.lagazette-mag.io\/en\/unnameddeco4-2\/"}],"amp_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"251\" src=\"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-300x251.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-150x126@2x.jpg 300w, https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-150x126.jpg 150w, https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-500x419.jpg 500w, https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4.jpg 1000w, https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-300x251@2x.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":837,"file":"unnamedDe\u0301co4.jpg","sizes":{"thumbnail":{"file":"unnamedDe\u0301co4-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-150x150.jpg"},"medium":{"file":"unnamedDe\u0301co4-300x251.jpg","width":300,"height":251,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-300x251.jpg"},"gg_gallery_thumbnail":{"file":"unnamedDe\u0301co4-450x250.jpg","width":450,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-450x250.jpg"},"bd-small":{"file":"unnamedDe\u0301co4-90x68.jpg","width":90,"height":68,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-90x68.jpg"},"bd-medium":{"file":"unnamedDe\u0301co4-310x165.jpg","width":310,"height":165,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-310x165.jpg"},"bd-large":{"file":"unnamedDe\u0301co4-560x370.jpg","width":560,"height":370,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-560x370.jpg"},"bd-big":{"file":"unnamedDe\u0301co4-1000x526.jpg","width":1000,"height":526,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-1000x526.jpg"},"bd-normal":{"file":"unnamedDe\u0301co4-660x330.jpg","width":660,"height":330,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-660x330.jpg"},"post-thumbnail":{"file":"unnamedDe\u0301co4-660x330.jpg","width":660,"height":330,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-660x330.jpg"},"wpbdp-mini":{"file":"unnamedDe\u0301co4-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-50x50.jpg"},"wpbdp-thumb":{"file":"unnamedDe\u0301co4-150x126.jpg","width":150,"height":126,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-150x126.jpg"},"wpbdp-large":{"file":"unnamedDe\u0301co4-500x419.jpg","width":500,"height":419,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4-500x419.jpg"},"full":{"file":"unnamedDe\u0301co4.jpg","width":1000,"height":837,"mime_type":"image\/jpeg","source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.lagazette-mag.io\/wp-content\/uploads\/unnamedDe\u0301co4.jpg","_links":{"self":[{"href":"https:\/\/www.lagazette-mag.io\/en\/wp-json\/wp\/v2\/media\/32325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lagazette-mag.io\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.lagazette-mag.io\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.lagazette-mag.io\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lagazette-mag.io\/en\/wp-json\/wp\/v2\/comments?post=32325"}]}}